{"id":40462,"date":"2026-03-30T12:38:45","date_gmt":"2026-03-30T11:38:45","guid":{"rendered":"https:\/\/bigbuy.tupique.com\/produto\/mens-watch-tissot-chrono-xl\/"},"modified":"2026-05-11T20:03:18","modified_gmt":"2026-05-11T18:03:18","slug":"mens-watch-tissot-chrono-xl","status":"publish","type":"product","link":"https:\/\/bigbuy.tupique.com\/pt\/produto\/mens-watch-tissot-chrono-xl\/","title":{"rendered":"Montre Homme Tissot CHRONO XL"},"content":{"rendered":"<p>Si vous \u00eates \u00e0 la recherche de nouvelles tendances sur le march\u00e9, nous vous pr\u00e9sentons <b>Montre Homme Tissot CHRONO XL<\/b> !<\/p>\n<ul>\n<li>Genre: Homme<\/li>\n<li>Liens suppl\u00e9mentaires: Non<\/li>\n<li>Type de montre: Montre-bracelet<\/li>\n<li>Inclut: Inclut un \u00e9tui ou une housse de la marque<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous \u00eates \u00e0 la recherche de nouvelles tendances sur le march\u00e9, nous vous pr\u00e9sentons Montre Homme Tissot CHRONO XL ! Genre: Homme Liens suppl\u00e9mentaires: Non Type de montre: Montre-bracelet Inclut: Inclut un \u00e9tui ou une housse de la marque<\/p>","protected":false},"featured_media":40456,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[794],"product_cat":[544,574,545],"product_tag":[103,543],"class_list":{"0":"post-40462","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_1719","7":"product_cat-mode-accessoires","8":"product_cat-montres-homme","9":"product_cat-montres-bracelets","10":"product_tag-tag_1261","11":"product_tag-tag_61","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product\/40462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/comments?post=40462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/media\/40456"}],"wp:attachment":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/media?parent=40462"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_brand?post=40462"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_cat?post=40462"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_tag?post=40462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}