{"id":18667,"date":"2026-03-29T15:38:06","date_gmt":"2026-03-29T14:38:06","guid":{"rendered":"https:\/\/bigbuy.tupique.com\/produto\/mens-watch-festina-f20563-1-grey\/"},"modified":"2026-05-11T20:03:40","modified_gmt":"2026-05-11T18:03:40","slug":"mens-watch-festina-f20563-1-grey","status":"publish","type":"product","link":"https:\/\/bigbuy.tupique.com\/pt\/produto\/mens-watch-festina-f20563-1-grey\/","title":{"rendered":"Montre Homme Festina F20563\/1 Gris"},"content":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez <b>Montre Homme Festina F20563\/1 Gris<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Genre: Homme<\/li>\n<li>Liens suppl\u00e9mentaires: Non<\/li>\n<li>Type de montre: Montre-bracelet<\/li>\n<li>Couleur: Gris<\/li>\n<li>Mat\u00e9riau du bracelet: Acier inoxydable<\/li>\n<li>Materiau du bo\u00eetier: Acier inoxydable<\/li>\n<li>Couleur du bracelet: Multicouleur<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez Montre Homme Festina F20563\/1 Gris au meilleur prix. Genre: Homme Liens suppl\u00e9mentaires: Non Type de montre: Montre-bracelet Couleur: Gris Mat\u00e9riau du bracelet: Acier inoxydable Materiau du bo\u00eetier: Acier inoxydable Couleur du bracelet: Multicouleur<\/p>","protected":false},"featured_media":18665,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[986],"product_cat":[544,574,545],"product_tag":[103,543],"class_list":{"0":"post-18667","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_830","7":"product_cat-mode-accessoires","8":"product_cat-montres-homme","9":"product_cat-montres-bracelets","10":"product_tag-tag_1261","11":"product_tag-tag_61","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product\/18667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/comments?post=18667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/media\/18665"}],"wp:attachment":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/media?parent=18667"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_brand?post=18667"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_cat?post=18667"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_tag?post=18667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}