{"id":17308,"date":"2026-03-29T14:33:43","date_gmt":"2026-03-29T13:33:43","guid":{"rendered":"https:\/\/bigbuy.tupique.com\/produto\/ladies-watch-ingersoll-1892-i12303\/"},"modified":"2026-05-11T20:03:28","modified_gmt":"2026-05-11T18:03:28","slug":"ladies-watch-ingersoll-1892-i12303","status":"publish","type":"product","link":"https:\/\/bigbuy.tupique.com\/pt\/produto\/ladies-watch-ingersoll-1892-i12303\/","title":{"rendered":"Montre Femme Ingersoll 1892 I12303"},"content":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez <b>Montre Femme Ingersoll 1892 I12303<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Genre: Femme<\/li>\n<li>Liens suppl\u00e9mentaires: Non<\/li>\n<li>Type de montre: Montre-bracelet<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez Montre Femme Ingersoll 1892 I12303 au meilleur prix. Genre: Femme Liens suppl\u00e9mentaires: Non Type de montre: Montre-bracelet<\/p>","protected":false},"featured_media":17306,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[835],"product_cat":[544,546,545],"product_tag":[103,542,543],"class_list":{"0":"post-17308","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_7989","7":"product_cat-mode-accessoires","8":"product_cat-montres-femme","9":"product_cat-montres-bracelets","10":"product_tag-tag_1261","11":"product_tag-tag_1274","12":"product_tag-tag_61","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product\/17308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/comments?post=17308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/media\/17306"}],"wp:attachment":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/media?parent=17308"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_brand?post=17308"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_cat?post=17308"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_tag?post=17308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}