{"id":16387,"date":"2026-03-29T13:38:57","date_gmt":"2026-03-29T12:38:57","guid":{"rendered":"https:\/\/bigbuy.tupique.com\/produto\/mens-watch-seiko-srpd51k1\/"},"modified":"2026-05-11T20:03:29","modified_gmt":"2026-05-11T18:03:29","slug":"mens-watch-seiko-srpd51k1","status":"publish","type":"product","link":"https:\/\/bigbuy.tupique.com\/pt\/produto\/mens-watch-seiko-srpd51k1\/","title":{"rendered":"Montre Homme Seiko SRPD51K1"},"content":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez <b>Montre Homme Seiko SRPD51K1<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Genre: Homme<\/li>\n<li>Liens suppl\u00e9mentaires: Non<\/li>\n<li>Type de montre: Montre-bracelet<\/li>\n<li>Mat\u00e9riau du bracelet: Acier inoxydable<\/li>\n<li>Materiau du bo\u00eetier: Acier inoxydable<\/li>\n<li>Couleur du cadran: Bleu<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez Montre Homme Seiko SRPD51K1 au meilleur prix. Genre: Homme Liens suppl\u00e9mentaires: Non Type de montre: Montre-bracelet Mat\u00e9riau du bracelet: Acier inoxydable Materiau du bo\u00eetier: Acier inoxydable Couleur du cadran: Bleu<\/p>","protected":false},"featured_media":179066,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[802],"product_cat":[544,574,545],"product_tag":[103,543],"class_list":{"0":"post-16387","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_879","7":"product_cat-mode-accessoires","8":"product_cat-montres-homme","9":"product_cat-montres-bracelets","10":"product_tag-tag_1261","11":"product_tag-tag_61","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product\/16387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/comments?post=16387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/media\/179066"}],"wp:attachment":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/media?parent=16387"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_brand?post=16387"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_cat?post=16387"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_tag?post=16387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}