{"id":159077,"date":"2026-04-09T20:08:34","date_gmt":"2026-04-09T19:08:34","guid":{"rendered":"https:\/\/bigbuy.tupique.com\/produto\/wireless-phone-cointra-white\/"},"modified":"2026-04-15T09:09:55","modified_gmt":"2026-04-15T08:09:55","slug":"wireless-phone-cointra-white","status":"publish","type":"product","link":"https:\/\/bigbuy.tupique.com\/pt\/produto\/wireless-phone-cointra-white\/","title":{"rendered":"T\u00e9l\u00e9phone Sans Fil Cointra Blanc"},"content":{"rendered":"<p>Si vous \u00eates passionn\u00e9 d&#8217;<b>informatique et d&#8217;\u00e9lectronique<\/b>, si vous \u00eates \u00e0 la pointe de la technologie et qu&#8217;aucun d\u00e9tail ne vous \u00e9chappe, achetez <b>T\u00e9l\u00e9phone Sans Fil Cointra Blanc<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Type: T\u00e9l\u00e9phone Sans Fil<\/li>\n<li>Produit \u00e0 brancher: Oui<\/li>\n<li>Bloc d\u2019Alimentation:\n<ul>\n<li>Batterie<\/li>\n<li>r\u00e9seau \u00e9lectrique<\/li>\n<\/ul>\n<\/li>\n<li>Type de prise: Prise EU<\/li>\n<li>Couleur: Blanc<\/li>\n<li>Classification \u00e9nerg\u00e9tique: A<\/li>\n<li>Profondeur: 25 cm<\/li>\n<li>Inclut: Ecran<\/li>\n<li>Type de commande: Boutons<\/li>\n<li>Longueur: 70 cm<\/li>\n<li>Design: Vertical<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><span class=\"unit-info\">1661.4143 &euro; \/ 1 m<\/span><\/p>","protected":false},"featured_media":159075,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[1605],"product_cat":[575,65,1050],"product_tag":[566,106],"class_list":{"0":"post-159077","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_1169","7":"product_cat-electronique-telephonie-et-tablettes","8":"product_cat-informatique-electronique","9":"product_cat-telephones-fixes-et-ip","10":"product_tag-tag_547","11":"product_tag-tag_1295","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product\/159077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/comments?post=159077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/media\/159075"}],"wp:attachment":[{"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/media?parent=159077"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_brand?post=159077"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_cat?post=159077"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/pt\/wp-json\/wp\/v2\/product_tag?post=159077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}