{"id":54587,"date":"2026-03-31T08:58:44","date_gmt":"2026-03-31T07:58:44","guid":{"rendered":"https:\/\/bigbuy.tupique.com\/produto\/video-conferencing-system-logitech-rally-ultra-hd\/"},"modified":"2026-05-11T19:59:12","modified_gmt":"2026-05-11T17:59:12","slug":"video-conferencing-system-logitech-rally-ultra-hd","status":"publish","type":"product","link":"https:\/\/bigbuy.tupique.com\/es\/produto\/video-conferencing-system-logitech-rally-ultra-hd\/","title":{"rendered":"Syst\u00e8me de Vid\u00e9oconf\u00e9rence Logitech Rally Ultra-HD"},"content":{"rendered":"<p>Si vous \u00eates passionn\u00e9 d&#8217;<b>informatique et d&#8217;\u00e9lectronique<\/b>, si vous \u00eates \u00e0 la pointe de la technologie et qu&#8217;aucun d\u00e9tail ne vous \u00e9chappe, achetez <b>Syst\u00e8me de Vid\u00e9oconf\u00e9rence Logitech Rally Ultra-HD<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Couleur: Noir<\/li>\n<li>Connexions:\n<ul>\n<li>HDMI x 2<\/li>\n<li>RJ45 x 2<\/li>\n<\/ul>\n<\/li>\n<li>Type:\n<ul>\n<li>Avec fil<\/li>\n<li>Syst\u00e8me de Vid\u00e9oconf\u00e9rence<\/li>\n<\/ul>\n<\/li>\n<li>Bloc d\u2019Alimentation: Courant alternatif<\/li>\n<li>Non inclut: Accessoires<\/li>\n<li>Inclut: Hub<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous \u00eates passionn\u00e9 d&#8217;informatique et d&#8217;\u00e9lectronique, si vous \u00eates \u00e0 la pointe de la technologie et qu&#8217;aucun d\u00e9tail ne vous \u00e9chappe, achetez Syst\u00e8me de Vid\u00e9oconf\u00e9rence Logitech Rally Ultra-HD au meilleur prix. Couleur: Noir Connexions: HDMI x 2 RJ45 x 2 Type: Avec fil Syst\u00e8me de Vid\u00e9oconf\u00e9rence Bloc d\u2019Alimentation: Courant alternatif Non inclut: Accessoires Inclut: [&hellip;]<\/p>\n","protected":false},"featured_media":54584,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[647],"product_cat":[65,581,607],"product_tag":[213,106],"class_list":{"0":"post-54587","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_561","7":"product_cat-informatique-electronique","8":"product_cat-informatique-peripheriques-et-consommables","9":"product_cat-webcam","10":"product_tag-tag_933","11":"product_tag-tag_1295","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product\/54587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/comments?post=54587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/media\/54584"}],"wp:attachment":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/media?parent=54587"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_brand?post=54587"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_cat?post=54587"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_tag?post=54587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}