{"id":22363,"date":"2026-03-29T18:45:32","date_gmt":"2026-03-29T17:45:32","guid":{"rendered":"https:\/\/bigbuy.tupique.com\/produto\/mens-watch-breil-tw2016-black-o-43-mm\/"},"modified":"2026-05-11T20:03:03","modified_gmt":"2026-05-11T18:03:03","slug":"mens-watch-breil-tw2016-black-o-43-mm","status":"publish","type":"product","link":"https:\/\/bigbuy.tupique.com\/es\/produto\/mens-watch-breil-tw2016-black-o-43-mm\/","title":{"rendered":"Montre Homme Breil TW2016 Noir (\u00d8 43 mm)"},"content":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez <b>Montre Homme Breil TW2016 Noir (\u00d8 43 mm)<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Liens suppl\u00e9mentaires: Non<\/li>\n<li>Type de montre: Montre-bracelet<\/li>\n<li>Fonctions: Date<\/li>\n<li>Genre: Homme<\/li>\n<li>Inclut: Inclut un \u00e9tui ou une housse de la marque<\/li>\n<li>Imperm\u00e9abilit\u00e9: 20 atm<\/li>\n<li>Verre: Min\u00e9ral<\/li>\n<li>Type de mouvement: Quartz<\/li>\n<li>Diam\u00e8tre du bo\u00eetier de la montre: \u00d8 43 mm<\/li>\n<li>Couleur: Noir<\/li>\n<li>Materiau du bo\u00eetier: Acier inoxydable<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez Montre Homme Breil TW2016 Noir (\u00d8 43 mm) au meilleur prix. Liens suppl\u00e9mentaires: Non Type de montre: Montre-bracelet Fonctions: Date Genre: Homme Inclut: Inclut un \u00e9tui ou une housse de la marque Imperm\u00e9abilit\u00e9: 20 atm Verre: Min\u00e9ral Type de mouvement: Quartz [&hellip;]<\/p>\n","protected":false},"featured_media":22361,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[1006],"product_cat":[544,574,545],"product_tag":[103],"class_list":{"0":"post-22363","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_809","7":"product_cat-mode-accessoires","8":"product_cat-montres-homme","9":"product_cat-montres-bracelets","10":"product_tag-tag_1261","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product\/22363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/comments?post=22363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/media\/22361"}],"wp:attachment":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/media?parent=22363"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_brand?post=22363"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_cat?post=22363"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_tag?post=22363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}