{"id":16981,"date":"2026-03-29T14:13:59","date_gmt":"2026-03-29T13:13:59","guid":{"rendered":"https:\/\/bigbuy.tupique.com\/produto\/mens-watch-bulova-98b203\/"},"modified":"2026-05-11T20:03:29","modified_gmt":"2026-05-11T18:03:29","slug":"mens-watch-bulova-98b203","status":"publish","type":"product","link":"https:\/\/bigbuy.tupique.com\/es\/produto\/mens-watch-bulova-98b203\/","title":{"rendered":"Montre Homme Bulova 98B203"},"content":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez <b>Montre Homme Bulova 98B203<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Genre: Homme<\/li>\n<li>Liens suppl\u00e9mentaires: Non<\/li>\n<li>Type de montre: Montre-bracelet<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez Montre Homme Bulova 98B203 au meilleur prix. Genre: Homme Liens suppl\u00e9mentaires: Non Type de montre: Montre-bracelet<\/p>","protected":false},"featured_media":16979,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[803],"product_cat":[544,744,545],"product_tag":[103,543],"class_list":{"0":"post-16981","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_810","7":"product_cat-mode-accessoires","8":"product_cat-montres-unisexe","9":"product_cat-montres-bracelets","10":"product_tag-tag_1261","11":"product_tag-tag_61","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product\/16981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/comments?post=16981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/media\/16979"}],"wp:attachment":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/media?parent=16981"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_brand?post=16981"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_cat?post=16981"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_tag?post=16981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}