{"id":16491,"date":"2026-03-29T13:41:23","date_gmt":"2026-03-29T12:41:23","guid":{"rendered":"https:\/\/bigbuy.tupique.com\/produto\/mens-watch-mido-m026-430-11-051-00\/"},"modified":"2026-05-11T20:03:33","modified_gmt":"2026-05-11T18:03:33","slug":"mens-watch-mido-m026-430-11-051-00","status":"publish","type":"product","link":"https:\/\/bigbuy.tupique.com\/es\/produto\/mens-watch-mido-m026-430-11-051-00\/","title":{"rendered":"Montre Homme Mido M026-430-11-051-00"},"content":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez <b>Montre Homme Mido M026-430-11-051-00<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Liens suppl\u00e9mentaires: Non<\/li>\n<li>Genre: Homme<\/li>\n<li>Type de montre: Montre-bracelet<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous aimez suivre les derni\u00e8res tendances en mati\u00e8re de mode et accessoires, achetez Montre Homme Mido M026-430-11-051-00 au meilleur prix. Liens suppl\u00e9mentaires: Non Genre: Homme Type de montre: Montre-bracelet<\/p>","protected":false},"featured_media":16487,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[796],"product_cat":[544,574,545],"product_tag":[103,543],"class_list":{"0":"post-16491","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_6824","7":"product_cat-mode-accessoires","8":"product_cat-montres-homme","9":"product_cat-montres-bracelets","10":"product_tag-tag_1261","11":"product_tag-tag_61","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product\/16491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/comments?post=16491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/media\/16487"}],"wp:attachment":[{"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/media?parent=16491"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_brand?post=16491"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_cat?post=16491"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/es\/wp-json\/wp\/v2\/product_tag?post=16491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}