{"id":18331,"date":"2026-03-29T15:20:17","date_gmt":"2026-03-29T14:20:17","guid":{"rendered":"https:\/\/bigbuy.tupique.com\/produto\/surveillance-camcorder-axis-p3248-4k-ultra-hd\/"},"modified":"2026-05-11T19:58:34","modified_gmt":"2026-05-11T17:58:34","slug":"surveillance-camcorder-axis-p3248-4k-ultra-hd","status":"publish","type":"product","link":"https:\/\/bigbuy.tupique.com\/en\/produto\/surveillance-camcorder-axis-p3248-4k-ultra-hd\/","title":{"rendered":"Camescope de surveillance Axis P3248 4K Ultra HD"},"content":{"rendered":"<p>Si vous \u00eates passionn\u00e9 d&#8217;<b>informatique et d&#8217;\u00e9lectronique<\/b>, si vous \u00eates \u00e0 la pointe de la technologie et qu&#8217;aucun d\u00e9tail ne vous \u00e9chappe, achetez <b>Camescope de surveillance Axis P3248 4K Ultra HD<\/b> au meilleur prix.<\/p>\n<ul>\n<li>Type:\n<ul>\n<li>Avec fil<\/li>\n<li>Cam\u00e9scope<\/li>\n<li>Cam\u00e9ra de s\u00e9curit\u00e9 IP<\/li>\n<\/ul>\n<\/li>\n<li>Connexions:\n<ul>\n<li>Ethernet LAN<\/li>\n<li>PoE x 1<\/li>\n<\/ul>\n<\/li>\n<li>Couleur:\n<ul>\n<li>Blanc<\/li>\n<li>Noir<\/li>\n<\/ul>\n<\/li>\n<li>R\u00e9solution: 4K Ultra HD<\/li>\n<li>M\u00e9moire interne: 2 GB<\/li>\n<li>Capteur: CMOS<\/li>\n<li>Nombre de cam\u00e9ras: 1<\/li>\n<li>R\u00e9solution (px): 3840 x 2160 px<\/li>\n<li>Mati\u00e8re: Plastique<\/li>\n<li>Caract\u00e9ristiques: Contr\u00f4le de l&#8217;inclinaison<\/li>\n<li>Connectivit\u00e9: Wi-Fi<\/li>\n<li>Cha\u00eenes: 4<\/li>\n<li>Classification IP: IP56<\/li>\n<li>Technologie: HDD<\/li>\n<li>Non inclut:\n<ul>\n<li>Wi-Fi<\/li>\n<li>Bluetooth<\/li>\n<\/ul>\n<\/li>\n<li>Facteur de forme: Balle<\/li>\n<li>Paire de lunettes: x1<\/li>\n<li>Inclut: Manuel de l&#8217;utilisateur<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Si vous \u00eates passionn\u00e9 d&#8217;informatique et d&#8217;\u00e9lectronique, si vous \u00eates \u00e0 la pointe de la technologie et qu&#8217;aucun d\u00e9tail ne vous \u00e9chappe, achetez Camescope de surveillance Axis P3248 4K Ultra HD au meilleur prix. Type: Avec fil Cam\u00e9scope Cam\u00e9ra de s\u00e9curit\u00e9 IP Connexions: Ethernet LAN PoE x 1 Couleur: Blanc Noir R\u00e9solution: 4K Ultra HD [&hellip;]<\/p>\n","protected":false},"featured_media":18327,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[645],"product_cat":[580,239,579],"product_tag":[567,210],"class_list":{"0":"post-18331","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-brandp_4776","7":"product_cat-cameras-de-surveillance-video","8":"product_cat-maison-jardin","9":"product_cat-securite-a-la-maison","10":"product_tag-tag_556","11":"product_tag-tag_25","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bigbuy.tupique.com\/en\/wp-json\/wp\/v2\/product\/18331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigbuy.tupique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bigbuy.tupique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/en\/wp-json\/wp\/v2\/comments?post=18331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/en\/wp-json\/wp\/v2\/media\/18327"}],"wp:attachment":[{"href":"https:\/\/bigbuy.tupique.com\/en\/wp-json\/wp\/v2\/media?parent=18331"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/en\/wp-json\/wp\/v2\/product_brand?post=18331"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/en\/wp-json\/wp\/v2\/product_cat?post=18331"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bigbuy.tupique.com\/en\/wp-json\/wp\/v2\/product_tag?post=18331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}